{"id":6747,"date":"2026-04-13T10:37:55","date_gmt":"2026-04-13T00:37:55","guid":{"rendered":"https:\/\/mstglobal.com\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/"},"modified":"2026-07-10T12:21:52","modified_gmt":"2026-07-10T02:21:52","slug":"avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit","status":"publish","type":"post","link":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/","title":{"rendered":"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Conferencia CIIT LATAM2026, del 26 al 27 de marzo  <\/h2>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">MST tuvo el orgullo de participar en <strong>el CIIT LATAM 2026<\/strong> en Lima, Per\u00fa, el Congreso Internacional de Innovaci\u00f3n Tecnol\u00f3gica centrado en la miner\u00eda, la energ\u00eda y la industria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento, que tuvo lugar los <strong>d\u00edas 26 y 27 de marzo<\/strong>, reuni\u00f3 a figuras clave del sector <strong>,<\/strong> como <strong>Komatsu Mitsui, Modular y MST,<\/strong> y puso de relieve los \u00faltimos avances que est\u00e1n marcando el futuro de la miner\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento, MST uni\u00f3 fuerzas con Komatsu y Modular en un <strong>stand compartido bajo la marca Komatsu<\/strong>, creando una presencia s\u00f3lida y unificada y estableciendo contacto con l\u00edderes del sector de toda la regi\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Creando una soluci\u00f3n integral&#8230; Subterr\u00e1nea + Superficial <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">CIIT LATAM sigue siendo una plataforma importante para la colaboraci\u00f3n y la innovaci\u00f3n en todo el sector minero, y nos hace mucha ilusi\u00f3n formar parte de los debates que impulsan el avance de la industria.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"704\" style=\"aspect-ratio: 1280 \/ 704;\" width=\"1280\" controls=\"\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/One-Komatsu.mp4\" playsinline=\"\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s informaci\u00f3n sobre el evento: <a href=\"https:\/\/ciitlatamcongress.com\/\">https:\/\/ciitlatamcongress.com\/<\/a><\/p>\n<\/div>\n<\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Actividades de liderazgo intelectual<\/strong><\/h3>\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:26% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-scaled.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-768x1024.jpeg\" alt=\"\" class=\"wp-image-5850 size-full\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-768x1024.jpeg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-600x800.jpeg 600w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-1152x1536.jpeg 1152w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-1536x2048.jpeg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-1125x1500.jpeg 1125w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-scaled.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"wp-block-paragraph\">El equipo conjunto tambi\u00e9n contribuy\u00f3 al programa de la conferencia con dos ponencias muy interesantes:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udd39 <strong>MST y Modular:<\/strong> <em>C\u00f3mo mejorar la eficacia en la miner\u00eda subterr\u00e1nea y a cielo abierto<\/em>, presentado por Kenyn (MST) y Patrik (Modular)<br\/>\ud83d\udd39 <strong>Komatsu Mitsui:<\/strong> <em>Soluciones de automatizaci\u00f3n con maquinaria Komatsu<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Implicar al sector<\/strong><\/h3>\n\n<p class=\"wp-block-paragraph\">Durante los dos d\u00edas, los equipos conjuntos de MST, Modular y Komatsu interactuaron con clientes, socios y compa\u00f1eros del sector, compartiendo ideas, presentando soluciones y reafirmando nuestro compromiso con la innovaci\u00f3n en el sector minero.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14.png\"><img decoding=\"async\" width=\"563\" height=\"469\" data-id=\"5840\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14.png\" alt=\"\" class=\"wp-image-5840\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-scaled.jpg\"><img decoding=\"async\" width=\"1024\" height=\"643\" data-id=\"5827\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-1024x643.jpg\" alt=\"\" class=\"wp-image-5827\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-1024x643.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-800x503.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-768x483.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-1536x965.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-2048x1287.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-2-1500x942.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"5821\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-1024x682.jpg\" alt=\"\" class=\"wp-image-5821\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-1024x682.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-800x533.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-768x511.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-1536x1023.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-2048x1364.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-3-1500x999.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5825\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-1024x683.jpg\" alt=\"\" class=\"wp-image-5825\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-1024x683.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-800x533.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-768x512.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-1536x1024.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-2048x1365.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-4-1500x1000.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-1024x683.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5823\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-1024x683.jpg\" alt=\"\" class=\"wp-image-5823\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-1024x683.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-800x533.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-768x512.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-1536x1024.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-2048x1365.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-5-1500x1000.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-1024x683.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5829\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-1024x683.jpg\" alt=\"\" class=\"wp-image-5829\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-1024x683.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-800x533.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-768x512.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-1536x1024.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-2048x1365.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-6-1500x1000.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5831\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-1024x683.jpg\" alt=\"\" class=\"wp-image-5831\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-1024x683.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-800x533.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-768x512.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-1536x1024.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-2048x1365.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-7-1500x1000.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5833\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-1024x683.jpg\" alt=\"\" class=\"wp-image-5833\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-1024x683.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-800x533.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-768x512.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-1536x1024.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-2048x1365.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-8-1500x1000.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5835\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-768x1024.jpg\" alt=\"\" class=\"wp-image-5835\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-768x1024.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-600x800.jpg 600w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-1152x1536.jpg 1152w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-1536x2048.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-1125x1500.jpg 1125w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-9-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5836\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-768x1024.jpg\" alt=\"\" class=\"wp-image-5836\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-768x1024.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-600x800.jpg 600w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-1152x1536.jpg 1152w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-1536x2048.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-1125x1500.jpg 1125w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-10-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5848\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-768x1024.jpeg\" alt=\"\" class=\"wp-image-5848\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-768x1024.jpeg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-600x800.jpeg 600w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-1152x1536.jpeg 1152w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-1536x2048.jpeg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-1125x1500.jpeg 1125w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6475-scaled.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"5842\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-1024x768.jpeg\" alt=\"\" class=\"wp-image-5842\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-1024x768.jpeg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-800x600.jpeg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-768x576.jpeg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-1536x1152.jpeg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-2048x1536.jpeg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-12-1500x1125.jpeg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5850\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-768x1024.jpeg\" alt=\"\" class=\"wp-image-5850\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-768x1024.jpeg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-600x800.jpeg 600w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-1152x1536.jpeg 1152w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-1536x2048.jpeg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-1125x1500.jpeg 1125w, https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6504-scaled.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"5846\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-768x1024.jpeg\" alt=\"\" class=\"wp-image-5846\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-768x1024.jpeg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-600x800.jpeg 600w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-1152x1536.jpeg 1152w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-1536x2048.jpeg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-1125x1500.jpeg 1125w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-14-scaled.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5837\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-1024x683.jpg\" alt=\"\" class=\"wp-image-5837\" srcset=\"https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-1024x683.jpg 1024w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-800x533.jpg 800w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-768x512.jpg 768w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-1536x1024.jpg 1536w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-2048x1365.jpg 2048w, https:\/\/mstglobal.com\/wp-content\/uploads\/CIIT-11-1500x1000.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<p class=\"wp-block-paragraph\">#MSTGlobal #CIITLATAM #MiningInnovation #Komatsu #ModularMining #Automation #MiningTechnology<\/p>\n\n<h2 class=\"wp-block-heading\">Ponte en contacto con el equipo para saber m\u00e1s<\/h2>\n\n<div class=\"wp-block-leadin-hubspot-form-block\">\n\t\t\t<div\n\t\t\tclass=\"hs-form-frame\"\n\t\t\tdata-region=\"ap1\"\n\t\t\tdata-form-id=\"646bee6f-5b0e-43b1-a383-be123a256108\"\n\t\t\tdata-portal-id=\"443001065\"\n\t\t\t >\n\t\t\t<\/div>\n\t\t\t<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conferencia CIIT LATAM2026, del 26 al 27 de marzo MST tuvo el orgullo de participar en el CIIT LATAM 2026 en Lima, Per\u00fa, el Congreso Internacional de Innovaci\u00f3n Tecnol\u00f3gica centrado en la miner\u00eda, la energ\u00eda y la industria. El evento, que tuvo lugar los d\u00edas 26 y 27 de marzo, reuni\u00f3 a figuras clave del <\/p>\n","protected":false},"author":8,"featured_media":5853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[5],"tags":[142,138,96,86,118,140,135,80,141],"class_list":["post-6747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-updates","tag-automation","tag-ciitlatam","tag-situational-awareness","tag-underground-connectivity","tag-proximity-detection","tag-komatsu","tag-digital-mines","tag-underground-mining","tag-mining-technology"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT - MST Global<\/title>\n<meta name=\"description\" content=\"MST was proud to participate in CIIT LATAM 2026 in Lima, Peru \u2014 the International Congress of Technological Innovation focused on mining, energy, and industry.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT - MST Global\" \/>\n<meta property=\"og:description\" content=\"MST was proud to participate in CIIT LATAM 2026 in Lima, Peru \u2014 the International Congress of Technological Innovation focused on mining, energy, and industry.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/\" \/>\n<meta property=\"og:site_name\" content=\"MST Global\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T00:37:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T02:21:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6495-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pauline Battersby\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pauline Battersby\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/\"},\"author\":{\"name\":\"Pauline Battersby\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/f296d65786a93867af04647ef2ed826a\"},\"headline\":\"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT\",\"datePublished\":\"2026-04-13T00:37:55+00:00\",\"dateModified\":\"2026-07-10T02:21:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/\"},\"wordCount\":311,\"publisher\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/IMG_6495-scaled.jpeg\",\"keywords\":[\"Automation\",\"CIITLATAM\",\"Situational Awareness\",\"Underground Connectivity\",\"Proximity Detection\",\"Komatsu\",\"Digital Mines\",\"Underground Mining\",\"Mining technology\"],\"articleSection\":[\"Company Updates\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/\",\"name\":\"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT - MST Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/IMG_6495-scaled.jpeg\",\"datePublished\":\"2026-04-13T00:37:55+00:00\",\"dateModified\":\"2026-07-10T02:21:52+00:00\",\"description\":\"MST was proud to participate in CIIT LATAM 2026 in Lima, Peru \u2014 the International Congress of Technological Innovation focused on mining, energy, and industry.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/IMG_6495-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/IMG_6495-scaled.jpeg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Actualizaciones de la empresa\",\"item\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/category\\\/company-updates-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/\",\"name\":\"MST Global\",\"description\":\"By Peter J Rees\",\"publisher\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#organization\",\"name\":\"MST Global\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/mst-global-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/mst-global-logo-1.png\",\"width\":1886,\"height\":1077,\"caption\":\"MST Global\"},\"image\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#\\\/schema\\\/person\\\/f296d65786a93867af04647ef2ed826a\",\"name\":\"Pauline Battersby\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0256bb3db50f6122ad217aab377f0fd655ea3ade40fd0491aec85e6944408070?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0256bb3db50f6122ad217aab377f0fd655ea3ade40fd0491aec85e6944408070?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0256bb3db50f6122ad217aab377f0fd655ea3ade40fd0491aec85e6944408070?s=96&d=mm&r=g\",\"caption\":\"Pauline Battersby\"},\"url\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/author\\\/p-battersbymstglobal-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT - MST Global","description":"MST was proud to participate in CIIT LATAM 2026 in Lima, Peru \u2014 the International Congress of Technological Innovation focused on mining, energy, and industry.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/","og_locale":"es_ES","og_type":"article","og_title":"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT - MST Global","og_description":"MST was proud to participate in CIIT LATAM 2026 in Lima, Peru \u2014 the International Congress of Technological Innovation focused on mining, energy, and industry.","og_url":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/","og_site_name":"MST Global","article_published_time":"2026-04-13T00:37:55+00:00","article_modified_time":"2026-07-10T02:21:52+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6495-scaled.jpeg","type":"image\/jpeg"}],"author":"Pauline Battersby","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pauline Battersby","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/#article","isPartOf":{"@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/"},"author":{"name":"Pauline Battersby","@id":"https:\/\/mstglobal.com\/es\/#\/schema\/person\/f296d65786a93867af04647ef2ed826a"},"headline":"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT","datePublished":"2026-04-13T00:37:55+00:00","dateModified":"2026-07-10T02:21:52+00:00","mainEntityOfPage":{"@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/"},"wordCount":311,"publisher":{"@id":"https:\/\/mstglobal.com\/es\/#organization"},"image":{"@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/#primaryimage"},"thumbnailUrl":"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6495-scaled.jpeg","keywords":["Automation","CIITLATAM","Situational Awareness","Underground Connectivity","Proximity Detection","Komatsu","Digital Mines","Underground Mining","Mining technology"],"articleSection":["Company Updates"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/","url":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/","name":"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT - MST Global","isPartOf":{"@id":"https:\/\/mstglobal.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/#primaryimage"},"image":{"@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/#primaryimage"},"thumbnailUrl":"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6495-scaled.jpeg","datePublished":"2026-04-13T00:37:55+00:00","dateModified":"2026-07-10T02:21:52+00:00","description":"MST was proud to participate in CIIT LATAM 2026 in Lima, Peru \u2014 the International Congress of Technological Innovation focused on mining, energy, and industry.","breadcrumb":{"@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/#primaryimage","url":"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6495-scaled.jpeg","contentUrl":"https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6495-scaled.jpeg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mstglobal.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Actualizaciones de la empresa","item":"https:\/\/mstglobal.com\/es\/category\/company-updates-es\/"},{"@type":"ListItem","position":3,"name":"Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT"}]},{"@type":"WebSite","@id":"https:\/\/mstglobal.com\/es\/#website","url":"https:\/\/mstglobal.com\/es\/","name":"MST Global","description":"By Peter J Rees","publisher":{"@id":"https:\/\/mstglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mstglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mstglobal.com\/es\/#organization","name":"MST Global","url":"https:\/\/mstglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mstglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mstglobal.com\/wp-content\/uploads\/mst-global-logo-1.png","contentUrl":"https:\/\/mstglobal.com\/wp-content\/uploads\/mst-global-logo-1.png","width":1886,"height":1077,"caption":"MST Global"},"image":{"@id":"https:\/\/mstglobal.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mstglobal.com\/es\/#\/schema\/person\/f296d65786a93867af04647ef2ed826a","name":"Pauline Battersby","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0256bb3db50f6122ad217aab377f0fd655ea3ade40fd0491aec85e6944408070?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0256bb3db50f6122ad217aab377f0fd655ea3ade40fd0491aec85e6944408070?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0256bb3db50f6122ad217aab377f0fd655ea3ade40fd0491aec85e6944408070?s=96&d=mm&r=g","caption":"Pauline Battersby"},"url":"https:\/\/mstglobal.com\/es\/author\/p-battersbymstglobal-com\/"}]}},"_links":{"self":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/posts\/6747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/comments?post=6747"}],"version-history":[{"count":1,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/posts\/6747\/revisions"}],"predecessor-version":[{"id":6749,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/posts\/6747\/revisions\/6749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/media\/5853"}],"wp:attachment":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/media?parent=6747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/categories?post=6747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/tags?post=6747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}