{"id":1750,"date":"2016-01-25T09:16:51","date_gmt":"2016-01-24T23:16:51","guid":{"rendered":"https:\/\/mstglobalcom.wpenginepowered.com\/inicio\/"},"modified":"2026-07-10T12:09:11","modified_gmt":"2026-07-10T02:09:11","slug":"inicio","status":"publish","type":"page","link":"https:\/\/mstglobal.com\/es\/","title":{"rendered":"Inicio"},"content":{"rendered":"\n<div class=\"hero-video-banner\">\n    <video playsinline=\"playsinline\" autoplay=\"autoplay\" muted=\"muted\" loop=\"loop\">\n        <source src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/mst-hero-video-web.mp4\" type=\"video\/mp4\">\n    <\/video>\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-md-10 col-lg-9 col-xl-7 col-xxl-6 align-self-center\">\n                <div class=\"content-wrap\">\n                    <h1>Soluciones pioneras para el futuro de la miner\u00eda<\/h1>\n                    <p>Capacit\u00e1ndote para desenterrar la seguridad y la productividad.<\/p>\n                                            <a href=\"https:\/\/mstglobal.com\/es\/industrias\/\" target=\"_self\">Saber m\u00e1s<\/a>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"wp-block-group content-fullwidth\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-bootstrap-blocks-container container mb-2\">\n\t\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12\">\n\t\t\t\n\n    <ul class=\"icon-menu-block technology\">\n                                <li>\n                <a href=\"https:\/\/mstglobal.com\/es\/tecnologia\/soluciones-informaticas\/\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/icon-software-solutions.png\" alt=\"Software Solutions Icon\" \/>\n                    Soluciones inform\u00e1ticas                <\/a>\n            <\/li>\n                                <li>\n                <a href=\"https:\/\/mstglobal.com\/es\/tecnologia\/infraestructura-de-redes\/\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/icon-network-infrastructure.png\" alt=\"Network Infrastructure Icon\" \/>\n                    Infraestructura de redes                <\/a>\n            <\/li>\n                                <li>\n                <a href=\"https:\/\/mstglobal.com\/es\/tecnologia\/dispositivos-de-comunicacion\/\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/icon-communication-devices.png\" alt=\"Communication Devices Icon\" \/>\n                    Dispositivos de comunicaci\u00f3n                <\/a>\n            <\/li>\n                                <li>\n                <a href=\"https:\/\/mstglobal.com\/es\/tecnologia\/sensores-iot-y-automatizacion\/\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/icon-iot-automation.png\" alt=\"IoT Sensors &amp; Automation Icon\" \/>\n                    Sensores IoT y automatizaci\u00f3n                <\/a>\n            <\/li>\n                                <li>\n                <a href=\"https:\/\/mstglobal.com\/es\/tecnologia\/seguridad-y-seguimiento\/\" target=\"_self\">\n                    <img decoding=\"async\" src=\"https:\/\/mstglobal.com\/wp-content\/uploads\/icon-safety-tracking.png\" alt=\"Safety &amp; Tracking Icon\" \/>\n                    Seguridad y seguimiento                <\/a>\n            <\/li>\n            <\/ul>\n\n\t<\/div>\n\n<\/div>\n\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-group content-fullwidth shade pull-up\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-bootstrap-blocks-container container mb-2\">\n\t\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12 col-xl-10 text-center offset-xl-1\">\n\t\t\t\n\n<p class=\"lead mt-5 mt-md-4 mt-lg-5 wp-block-paragraph\">A lo largo de los \u00faltimos 30 a\u00f1os hemos entregado soluciones cada vez m\u00e1s innovadoras que no solo responden a las necesidades de hoy sino que tambi\u00e9n se adelantan a sus exigencias a futuro.<\/p>\n\n\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a\n\t\thref=\"https:\/\/mstglobal.com\/about\/\"\n\t\t\t\t\t\tclass=\"btn btn-lg my-3 btn-primary\"\n\t>\n\t\tM\u00e1s sobre nosotros\t<\/a>\n<\/div>\n\n\t<\/div>\n\n<\/div>\n\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-group content-fullwidth rev charcoal vector-bg pb-2x\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-bootstrap-blocks-container container mb-2\">\n\t\n<div class=\"wp-bootstrap-blocks-row row mb-4 mb-lg-5\">\n\t\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<h2 class=\"wp-block-heading lg\">Soluciones industriales<\/h2>\n\n\t<\/div>\n\n\n\n<div class=\"col-12 col-md-6\">\n\t\t\t\n\n<p class=\"lead-block wp-block-paragraph\">Solo la soluci\u00f3n correcta le ayudar\u00e1 a resolver sus problemas espec\u00edficos, sino recibir\u00e1 componentes parciales, que le entregar\u00e1n resultados a medias.<\/p>\n\n\t<\/div>\n\n<\/div>\n\n<\/div>\n\n\n\n<div class=\"container-fluid image-menu-block\">\n    <div class=\"row\">\n                                                    <div class=\"col-md-6 col-lg-3\">\n                    <div class=\"menu-item\">\n                        <a href=\"https:\/\/mstglobal.com\/es\/industrias\/mineria-subterranea-de-roca-dura\/\" target=\"_self\">\n                            <div class=\"bg-wrap\" style=\"background-image: url('https:\/\/mstglobal.com\/wp-content\/uploads\/solutions-underground-hard-rock-mining.jpg');\"><\/div>\n                            <div class=\"text-wrap\"><h3>Miner\u00eda subterr\u00e1nea de roca dura<\/h3><\/div>\n                        <\/a>\n                    <\/div>\n                <\/div>\n                                            <div class=\"col-md-6 col-lg-3\">\n                    <div class=\"menu-item\">\n                        <a href=\"https:\/\/mstglobal.com\/es\/industrias\/mineria-de-carbon-subterranea\/\" target=\"_self\">\n                            <div class=\"bg-wrap\" style=\"background-image: url('https:\/\/mstglobal.com\/wp-content\/uploads\/solutions-underground-coal-mining.jpg');\"><\/div>\n                            <div class=\"text-wrap\"><h3>Miner\u00eda de carb\u00f3n subterr\u00e1nea<\/h3><\/div>\n                        <\/a>\n                    <\/div>\n                <\/div>\n                                            <div class=\"col-md-6 col-lg-3\">\n                    <div class=\"menu-item\">\n                        <a href=\"https:\/\/mstglobal.com\/es\/industrias\/tuneleria\/\" target=\"_self\">\n                            <div class=\"bg-wrap\" style=\"background-image: url('https:\/\/mstglobal.com\/wp-content\/uploads\/solutions-tunneling.jpg');\"><\/div>\n                            <div class=\"text-wrap\"><h3>Tuneler\u00eda<\/h3><\/div>\n                        <\/a>\n                    <\/div>\n                <\/div>\n                                            <div class=\"col-md-6 col-lg-3\">\n                    <div class=\"menu-item\">\n                        <a href=\"https:\/\/mstglobal.com\/es\/industrias\/mineria-de-superficie\/\" target=\"_self\">\n                            <div class=\"bg-wrap\" style=\"background-image: url('https:\/\/mstglobal.com\/wp-content\/uploads\/solutions-surface-technologies.jpg');\"><\/div>\n                            <div class=\"text-wrap\"><h3>Surface Communication Network Technologies (APAC)<\/h3><\/div>\n                        <\/a>\n                    <\/div>\n                <\/div>\n                        <\/div>\n<\/div>\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">M\u00e1s informaci\u00f3n&#8230;<\/h2>\n\n\n<div class=\"wp-bootstrap-blocks-button text-center\">\n\t<a\n\t\thref=\"https:\/\/mstglobal.com\/wp-content\/uploads\/MST-Global-Capability-Statement-2026.pdf\"\n\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\trel=\"noreferrer noopener\"\n\t\t\t\tclass=\"btn btn-secondary\"\n\t>\n\t\tDescarga nuestra declaraci\u00f3n de capacidades para obras subterr\u00e1neas \u2192\t<\/a>\n<\/div>\n<\/div><\/div>\n\n\n<div id=\"recent-posts\" class=\"content-fullwidth\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-md-6 order-1 order-md-1\">\n                <h2 class=\"text-center text-md-start mb-4 mb-md-5\">\u00daltimas noticias de MST<\/h2>\n            <\/div>\n            <div class=\"col-md-6 order-3 order-md-2\">\n                <p class=\"cta-link text-center text-md-end mt-md-2\"><a href=\"https:\/\/mstglobal.com\/es\/noticias\/\">Ver todas<\/a><\/p>\n            <\/div>\n            <div class=\"col-md-12 order-2 order-md-3 mb-md-5\">\n                <div class=\"row row-eq-height\">\n                    \n                        <div class=\"col-md-4\">\n\n                            <article class=\"post-6745 post type-post status-publish format-standard has-post-thumbnail hentry category-company-updates category-product-information tag-helix-automation tag-underground-connectivity tag-dispatch-lite tag-dispatch-pro tag-fms tag-helix tag-helix-dispatch tag-improving-fleet-cycles tag-digital-mines tag-underground-mining tag-fleet-management-system tag-sls tag-smart-lighting-solution\" id=\"post-6745\">\n\n                                <a href=\"https:\/\/mstglobal.com\/es\/mst-global-se-asocia-con-mineglow\/\"><div class=\"featured-img\"><div class=\"bg-wrap\" style=\"background-image: url('https:\/\/mstglobal.com\/wp-content\/uploads\/Mineglow-1.png');\"><\/div><\/div>\n\n                                    <div class=\"post-content\">\n\n                                        <header class=\"entry-header\">\n\n                                            <h2 class=\"entry-title\">MST Global se asocia con MineGlow<\/h2>\n                                        <\/header><!-- .entry-header -->\n\n                                    <\/div><!-- .post-content -->\n                                <\/a>\n                            <\/article><!-- #post-## -->\n                        <\/div>\n\n                    \n                        <div class=\"col-md-4\">\n\n                            <article class=\"post-6747 post type-post status-publish format-standard has-post-thumbnail hentry category-company-updates tag-automation tag-ciitlatam tag-situational-awareness tag-underground-connectivity tag-proximity-detection tag-komatsu tag-digital-mines tag-underground-mining tag-mining-technology\" id=\"post-6747\">\n\n                                <a href=\"https:\/\/mstglobal.com\/es\/avances-en-tecnologia-minera-en-latinoamerica-en-el-ciit\/\"><div class=\"featured-img\"><div class=\"bg-wrap\" style=\"background-image: url('https:\/\/mstglobal.com\/wp-content\/uploads\/IMG_6495-800x600.jpeg');\"><\/div><\/div>\n\n                                    <div class=\"post-content\">\n\n                                        <header class=\"entry-header\">\n\n                                            <h2 class=\"entry-title\">Avances en tecnolog\u00eda minera en Latinoam\u00e9rica en el CIIT<\/h2>\n                                        <\/header><!-- .entry-header -->\n\n                                    <\/div><!-- .post-content -->\n                                <\/a>\n                            <\/article><!-- #post-## -->\n                        <\/div>\n\n                    \n                        <div class=\"col-md-4\">\n\n                            <article class=\"post-6750 post type-post status-publish format-standard has-post-thumbnail hentry category-product-information-es tag-minas-digitales tag-particulas-de-diesel tag-dispatch-lite tag-dispatch-pro tag-fms tag-sistema-de-gestion-de-flotas tag-conectividad-subterranea tag-helix-dispatch tag-mineria-subterranea\" id=\"post-6750\">\n\n                                <a href=\"https:\/\/mstglobal.com\/es\/lanzamiento-de-helix-1-6-un-paso-adelante-en-visibilidad-automatizacion-y-control\/\"><div class=\"featured-img\"><div class=\"bg-wrap\" style=\"background-image: url('https:\/\/mstglobal.com\/wp-content\/uploads\/HELIX-1.6-800x450.png');\"><\/div><\/div>\n\n                                    <div class=\"post-content\">\n\n                                        <header class=\"entry-header\">\n\n                                            <h2 class=\"entry-title\">Lanzamiento de HELIX 1.6: un paso adelante en visibilidad, automatizaci\u00f3n y control<\/h2>\n                                        <\/header><!-- .entry-header -->\n\n                                    <\/div><!-- .post-content -->\n                                <\/a>\n                            <\/article><!-- #post-## -->\n                        <\/div>\n\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<div class=\"wp-block-group cta-block hero\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-bootstrap-blocks-container container mb-2\">\n\t\n<div class=\"wp-bootstrap-blocks-row row\">\n\t\n\n<div class=\"col-12\">\n\t\t\t\n\n<h2 class=\"wp-block-heading\">Las operaciones complejas se combinan con soluciones efectivas y preparadas para el futuro.<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-e740e555c0bc5eeedbb0fc3a4dc63e73\">\u00bfNecesitas m\u00e1s informaci\u00f3n? Cont\u00e1ctanos para m\u00e1s informaci\u00f3n.  <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-bootstrap-blocks-button\">\n\t<a\n\t\thref=\"https:\/\/mstglobal.com\/es\/contacto\/\"\n\t\t\t\t\t\tclass=\"btn btn-lg btn-secondary-rev\"\n\t>\n\t\tInf\u00f3rmate hoy\t<\/a>\n<\/div>\n\n\t<\/div>\n\n<\/div>\n\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s informaci\u00f3n&#8230; <\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/homepage.php","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"class_list":["post-1750","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MST Global | Tu socio para la transformaci\u00f3n digital<\/title>\n<meta name=\"description\" content=\"Especialistas en el desarrollo de tecnolog\u00edas avanzadas que contribuyen a mejorar la seguridad y la productividad en entornos mineros e industriales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mstglobal.com\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Especialistas en transformaci\u00f3n digital de minas subterr\u00e1neas\" \/>\n<meta property=\"og:description\" content=\"Soluciones pioneras para el futuro de la miner\u00eda subterr\u00e1nea. Capacit\u00e1ndote para desenterrar la seguridad y la productividad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mstglobal.com\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"MST Global\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T02:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mstglobal.com\/wp-content\/uploads\/4925-x-3283-Software-Solutions-800x533.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/\",\"name\":\"MST Global | Tu socio para la transformaci\u00f3n digital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#website\"},\"datePublished\":\"2016-01-24T23:16:51+00:00\",\"dateModified\":\"2026-07-10T02:09:11+00:00\",\"description\":\"Especialistas en el desarrollo de tecnolog\u00edas avanzadas que contribuyen a mejorar la seguridad y la productividad en entornos mineros e industriales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mstglobal.com\\\/es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/\",\"name\":\"MST Global\",\"description\":\"By Peter J Rees\",\"publisher\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#organization\",\"name\":\"MST Global\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/mst-global-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/mstglobal.com\\\/wp-content\\\/uploads\\\/mst-global-logo-1.png\",\"width\":1886,\"height\":1077,\"caption\":\"MST Global\"},\"image\":{\"@id\":\"https:\\\/\\\/mstglobal.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MST Global | Tu socio para la transformaci\u00f3n digital","description":"Especialistas en el desarrollo de tecnolog\u00edas avanzadas que contribuyen a mejorar la seguridad y la productividad en entornos mineros e industriales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mstglobal.com\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Especialistas en transformaci\u00f3n digital de minas subterr\u00e1neas","og_description":"Soluciones pioneras para el futuro de la miner\u00eda subterr\u00e1nea. Capacit\u00e1ndote para desenterrar la seguridad y la productividad.","og_url":"https:\/\/mstglobal.com\/es\/","og_site_name":"MST Global","article_modified_time":"2026-07-10T02:09:11+00:00","og_image":[{"url":"https:\/\/mstglobal.com\/wp-content\/uploads\/4925-x-3283-Software-Solutions-800x533.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mstglobal.com\/es\/","url":"https:\/\/mstglobal.com\/es\/","name":"MST Global | Tu socio para la transformaci\u00f3n digital","isPartOf":{"@id":"https:\/\/mstglobal.com\/es\/#website"},"datePublished":"2016-01-24T23:16:51+00:00","dateModified":"2026-07-10T02:09:11+00:00","description":"Especialistas en el desarrollo de tecnolog\u00edas avanzadas que contribuyen a mejorar la seguridad y la productividad en entornos mineros e industriales.","breadcrumb":{"@id":"https:\/\/mstglobal.com\/es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mstglobal.com\/es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mstglobal.com\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mstglobal.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Inicio"}]},{"@type":"WebSite","@id":"https:\/\/mstglobal.com\/es\/#website","url":"https:\/\/mstglobal.com\/es\/","name":"MST Global","description":"By Peter J Rees","publisher":{"@id":"https:\/\/mstglobal.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mstglobal.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mstglobal.com\/es\/#organization","name":"MST Global","url":"https:\/\/mstglobal.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mstglobal.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mstglobal.com\/wp-content\/uploads\/mst-global-logo-1.png","contentUrl":"https:\/\/mstglobal.com\/wp-content\/uploads\/mst-global-logo-1.png","width":1886,"height":1077,"caption":"MST Global"},"image":{"@id":"https:\/\/mstglobal.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/pages\/1750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/comments?post=1750"}],"version-history":[{"count":2,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/pages\/1750\/revisions"}],"predecessor-version":[{"id":6731,"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/pages\/1750\/revisions\/6731"}],"wp:attachment":[{"href":"https:\/\/mstglobal.com\/es\/wp-json\/wp\/v2\/media?parent=1750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}